{"id":732,"date":"2021-06-11T16:21:28","date_gmt":"2021-06-11T16:21:28","guid":{"rendered":"http:\/\/medica-tec.com\/chile\/?p=732"},"modified":"2021-06-22T13:11:04","modified_gmt":"2021-06-22T13:11:04","slug":"medios-de-prueba-microbiologicos-listos-para-usar","status":"publish","type":"post","link":"https:\/\/medica-tec.com\/chile\/medios-de-prueba-microbiologicos-listos-para-usar\/","title":{"rendered":"Medios de Prueba Microbiol\u00f3gicos Listos Para Usar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Como se refleja en la Ley de Higiene de los Alimentos y la implementaci\u00f3n de la Ley de Responsabilidad por Productos, garantizar la seguridad de los alimentos se ha convertido en una preocupaci\u00f3n social a\u00fan mayor en Jap\u00f3n.&nbsp;Bas\u00e1ndose en su amplia experiencia y logros en el campo de los agentes de diagn\u00f3stico cl\u00ednico, Nissui Pharmaceutical ofrece medios de prueba microbiol\u00f3gicos f\u00e1ciles de usar y una amplia variedad de productos que son compatibles con el an\u00e1lisis de peligros y los puntos cr\u00edticos de control (HACCP).<br>Adem\u00e1s, nuestro principal producto <strong>Compact Dry<\/strong> ha sido certificado por la Asociaci\u00f3n de Qu\u00edmicos Anal\u00edticos Oficiales (AOAC), en los EE. UU., La instituci\u00f3n m\u00e1s autorizada del mundo para certificar m\u00e9todos anal\u00edticos para productos alimenticios y detectar e inmovilizar microorganismos.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-red-background-color has-text-color has-background\" href=\"http:\/\/medica-tec.com\/chile\/wp-content\/uploads\/sites\/6\/2021\/06\/Nota-Tecnica-Medios-de-prueba-microbiologicos-listos-para-usar.pdf\">Descargar Nota T\u00e9cnica<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como se refleja en la Ley de Higiene de los Alimentos y la implementaci\u00f3n de la Ley de Responsabilidad por [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-tecnicas"],"_links":{"self":[{"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/posts\/732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/comments?post=732"}],"version-history":[{"count":2,"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/posts\/732\/revisions"}],"predecessor-version":[{"id":744,"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/posts\/732\/revisions\/744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/media\/743"}],"wp:attachment":[{"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/media?parent=732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/categories?post=732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medica-tec.com\/chile\/wp-json\/wp\/v2\/tags?post=732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}